{"id":1041,"date":"2010-11-19T09:09:27","date_gmt":"2010-11-19T09:09:27","guid":{"rendered":"http:\/\/asiattorney.amagumolabs.io\/labour-legal-updates-on-labor-law\/"},"modified":"2018-06-06T09:11:40","modified_gmt":"2018-06-06T09:11:40","slug":"labour-legal-updates-on-labor-law","status":"publish","type":"post","link":"https:\/\/www.asiattorney.com\/fr\/labour-legal-updates-on-labor-law\/","title":{"rendered":"L&rsquo;actualit\u00e9 en droit du travail"},"content":{"rendered":"<p><em>19 novembre 2010 \u00e0 Hanoi:\u00a0<\/em>Caroline Chazard a pr\u00e9sent\u00e9 l&rsquo;<strong>actualit\u00e9 en droit du travail<\/strong>\u00a0lors de la Table-Ronde Ressources Humaines organis\u00e9e par la CCIFV anim\u00e9e par Philippe Dendievel: \u00ab\u00a0Comment identifier et s\u00e9lectionner aujourd&rsquo;hui vos collaborateurs qualifi\u00e9s et votre encadrement au Vietnam\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>19 novembre 2010 \u00e0 Hanoi:\u00a0Caroline Chazard a pr\u00e9sent\u00e9 l&rsquo;actualit\u00e9 en droit du travail\u00a0lors de la Table-Ronde Ressources Humaines organis\u00e9e par la CCIFV anim\u00e9e par Philippe Dendievel: \u00ab\u00a0Comment identifier et s\u00e9lectionner aujourd&rsquo;hui vos collaborateurs qualifi\u00e9s et votre encadrement au Vietnam\u00a0\u00bb.<\/p>\n","protected":false},"author":5,"featured_media":509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publication"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;actualit\u00e9 en droit du travail - Fidal Asiattorneys<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;actualit\u00e9 en droit du travail - Fidal Asiattorneys\" \/>\n<meta property=\"og:description\" content=\"19 novembre 2010 \u00e0 Hanoi:\u00a0Caroline Chazard a pr\u00e9sent\u00e9 l&rsquo;actualit\u00e9 en droit du travail\u00a0lors de la Table-Ronde Ressources Humaines organis\u00e9e par la CCIFV anim\u00e9e par Philippe Dendievel: \u00ab\u00a0Comment identifier et s\u00e9lectionner aujourd&rsquo;hui vos collaborateurs qualifi\u00e9s et votre encadrement au Vietnam\u00a0\u00bb.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/\" \/>\n<meta property=\"og:site_name\" content=\"Fidal Asiattorneys\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FidalAsiattorneys\" \/>\n<meta property=\"article:published_time\" content=\"2010-11-19T09:09:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-06T09:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/54.179.223.75\/wp-content\/uploads\/confauf.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"support@amagumolabs.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"support@amagumolabs.com\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/\"},\"author\":{\"name\":\"support@amagumolabs.com\",\"@id\":\"https:\/\/54.179.223.75\/#\/schema\/person\/37db6c8eab1b4be1010713b7b8e39923\"},\"headline\":\"L&rsquo;actualit\u00e9 en droit du travail\",\"datePublished\":\"2010-11-19T09:09:27+00:00\",\"dateModified\":\"2018-06-06T09:11:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/\"},\"wordCount\":51,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/54.179.223.75\/#organization\"},\"image\":{\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg\",\"articleSection\":[\"Publications\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/\",\"url\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/\",\"name\":\"L'actualit\u00e9 en droit du travail - Fidal Asiattorneys\",\"isPartOf\":{\"@id\":\"https:\/\/54.179.223.75\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg\",\"datePublished\":\"2010-11-19T09:09:27+00:00\",\"dateModified\":\"2018-06-06T09:11:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage\",\"url\":\"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg\",\"contentUrl\":\"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg\",\"width\":1280,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.asiattorney.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;actualit\u00e9 en droit du travail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/54.179.223.75\/#website\",\"url\":\"https:\/\/54.179.223.75\/\",\"name\":\"Fidal Asiattorneys\",\"description\":\"Your crossborder crossculture legal partner\",\"publisher\":{\"@id\":\"https:\/\/54.179.223.75\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/54.179.223.75\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/54.179.223.75\/#organization\",\"name\":\"Fidal Asiattorneys\",\"url\":\"https:\/\/54.179.223.75\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/54.179.223.75\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/asiattorney.com\/wp-content\/uploads\/fidal-logo.jpg\",\"contentUrl\":\"http:\/\/asiattorney.com\/wp-content\/uploads\/fidal-logo.jpg\",\"width\":311,\"height\":58,\"caption\":\"Fidal Asiattorneys\"},\"image\":{\"@id\":\"https:\/\/54.179.223.75\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FidalAsiattorneys\",\"https:\/\/www.linkedin.com\/company\/fidal-asiattorneys-vietnam\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/54.179.223.75\/#\/schema\/person\/37db6c8eab1b4be1010713b7b8e39923\",\"name\":\"support@amagumolabs.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/54.179.223.75\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d78d5171e0a5d6526bee15729529720a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d78d5171e0a5d6526bee15729529720a?s=96&d=mm&r=g\",\"caption\":\"support@amagumolabs.com\"},\"url\":\"https:\/\/www.asiattorney.com\/fr\/author\/supportamagumolabs-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'actualit\u00e9 en droit du travail - Fidal Asiattorneys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/","og_locale":"fr_FR","og_type":"article","og_title":"L'actualit\u00e9 en droit du travail - Fidal Asiattorneys","og_description":"19 novembre 2010 \u00e0 Hanoi:\u00a0Caroline Chazard a pr\u00e9sent\u00e9 l&rsquo;actualit\u00e9 en droit du travail\u00a0lors de la Table-Ronde Ressources Humaines organis\u00e9e par la CCIFV anim\u00e9e par Philippe Dendievel: \u00ab\u00a0Comment identifier et s\u00e9lectionner aujourd&rsquo;hui vos collaborateurs qualifi\u00e9s et votre encadrement au Vietnam\u00a0\u00bb.","og_url":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/","og_site_name":"Fidal Asiattorneys","article_publisher":"https:\/\/www.facebook.com\/FidalAsiattorneys","article_published_time":"2010-11-19T09:09:27+00:00","article_modified_time":"2018-06-06T09:11:40+00:00","og_image":[{"width":1280,"height":719,"url":"https:\/\/54.179.223.75\/wp-content\/uploads\/confauf.jpeg","type":"image\/jpeg"}],"author":"support@amagumolabs.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"support@amagumolabs.com"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#article","isPartOf":{"@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/"},"author":{"name":"support@amagumolabs.com","@id":"https:\/\/54.179.223.75\/#\/schema\/person\/37db6c8eab1b4be1010713b7b8e39923"},"headline":"L&rsquo;actualit\u00e9 en droit du travail","datePublished":"2010-11-19T09:09:27+00:00","dateModified":"2018-06-06T09:11:40+00:00","mainEntityOfPage":{"@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/"},"wordCount":51,"commentCount":0,"publisher":{"@id":"https:\/\/54.179.223.75\/#organization"},"image":{"@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg","articleSection":["Publications"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/","url":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/","name":"L'actualit\u00e9 en droit du travail - Fidal Asiattorneys","isPartOf":{"@id":"https:\/\/54.179.223.75\/#website"},"primaryImageOfPage":{"@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage"},"image":{"@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg","datePublished":"2010-11-19T09:09:27+00:00","dateModified":"2018-06-06T09:11:40+00:00","breadcrumb":{"@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#primaryimage","url":"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg","contentUrl":"https:\/\/www.asiattorney.com\/wp-content\/uploads\/confauf.jpeg","width":1280,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/54.179.223.75\/fr\/labour-legal-updates-on-labor-law\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asiattorney.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;actualit\u00e9 en droit du travail"}]},{"@type":"WebSite","@id":"https:\/\/54.179.223.75\/#website","url":"https:\/\/54.179.223.75\/","name":"Fidal Asiattorneys","description":"Your crossborder crossculture legal partner","publisher":{"@id":"https:\/\/54.179.223.75\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/54.179.223.75\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/54.179.223.75\/#organization","name":"Fidal Asiattorneys","url":"https:\/\/54.179.223.75\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/54.179.223.75\/#\/schema\/logo\/image\/","url":"http:\/\/asiattorney.com\/wp-content\/uploads\/fidal-logo.jpg","contentUrl":"http:\/\/asiattorney.com\/wp-content\/uploads\/fidal-logo.jpg","width":311,"height":58,"caption":"Fidal Asiattorneys"},"image":{"@id":"https:\/\/54.179.223.75\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FidalAsiattorneys","https:\/\/www.linkedin.com\/company\/fidal-asiattorneys-vietnam\/"]},{"@type":"Person","@id":"https:\/\/54.179.223.75\/#\/schema\/person\/37db6c8eab1b4be1010713b7b8e39923","name":"support@amagumolabs.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/54.179.223.75\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d78d5171e0a5d6526bee15729529720a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d78d5171e0a5d6526bee15729529720a?s=96&d=mm&r=g","caption":"support@amagumolabs.com"},"url":"https:\/\/www.asiattorney.com\/fr\/author\/supportamagumolabs-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/posts\/1041"}],"collection":[{"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/comments?post=1041"}],"version-history":[{"count":2,"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/posts\/1041\/revisions"}],"predecessor-version":[{"id":1044,"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/posts\/1041\/revisions\/1044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/media\/509"}],"wp:attachment":[{"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/media?parent=1041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/categories?post=1041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asiattorney.com\/fr\/wp-json\/wp\/v2\/tags?post=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}